{"id":335,"date":"2021-09-16T14:07:16","date_gmt":"2021-09-16T14:07:16","guid":{"rendered":"https:\/\/podcastestudios.com\/?p=335"},"modified":"2021-10-02T09:25:14","modified_gmt":"2021-10-02T09:25:14","slug":"turismo-y-podcasting-una-nueva-forma-de-conocer-el-territorio","status":"publish","type":"post","link":"https:\/\/podcastestudios.com\/es\/turismo-y-podcasting-una-nueva-forma-de-conocer-el-territorio\/","title":{"rendered":"Turismo y podcasting, una nueva forma de conocer el territorio"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Descubrir nuevos sitios tambi\u00e9n se puede hacer gracias al podcasting. A trav\u00e9s de c\u00e1psulas que nos ayudan a entender e interpretar el territorio, juntamos dos mundos: el turismo y el podcast. Es el caso de las Terres de l\u2019Ebre, con el <strong><a href=\"https:\/\/rctgn.cat\/podcast\/programes\/especials\/terres-de-lebre-cast\/rinconesebro-las-cases-dalcanar\/\" data-type=\"URL\" data-id=\"https:\/\/rctgn.cat\/podcast\/programes\/especials\/terres-de-lebre-cast\/rinconesebro-las-cases-dalcanar\/\" target=\"_blank\" rel=\"noreferrer noopener\">podcast Rincones por Descubrir de las Terres de l\u2019Ebre<\/a><\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mediante una audiodescripcci\u00f3n de los parajes m\u00e1s destacados de la zona, recreamos un <strong>paisaje sonoro que sumerge el oyente en la realidad natural y social de las Terres de l\u2019Ebre<\/strong>. Presentamos el contenido en dos idiomas, catal\u00e1n y castellano, apostando por un <strong>formato ampliable a otras lenguas<\/strong>, como el ingl\u00e9s o el frances, gracias a un servicio de doblaje.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Versi\u00f3n en castellano:<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-spotify wp-block-embed-spotify wp-embed-aspect-21-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Spotify Embed: Rincones por descubrir de las Terres de l\u2019Ebre \u2013 R\u00e0dio Ciutat de Tarragona\" width=\"100%\" height=\"152\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" src=\"https:\/\/open.spotify.com\/embed\/show\/2FK3q6jevWeJQN9Y3Ip66h\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Versi\u00f3n en catal\u00e1n:<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-spotify wp-block-embed-spotify wp-embed-aspect-21-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Spotify Embed: #RaconsEbre | Les Cases d\u2019Alcanar\" width=\"100%\" height=\"152\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" src=\"https:\/\/open.spotify.com\/embed\/episode\/2hUQvYlE1febw6kj4oXupH?si=9mEq6n5WS1CoOC207_rQ6Q&#038;dl_branch=1\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En Rincones por Descubrir de las Terres de l\u2019Ebre hemos presentado varios sitios, como la Punta del Duque, la Reserva de Sebes, las Cases d\u2019Alcanar o l\u2019Ametlla de Mar.<strong> Zonas muy tur\u00edsticas, con muchas historia y una gran riqueza natural<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde el trabajo de los pescadores \u2018caleros\u2019 hasta un paseo por los caminos m\u00e1s emblem\u00e1ticos del Ebro, pasando por los sonidos caracter\u00edsticos de la fauna aut\u00f3ctona, Rincones por Descubrir de las Terras de l\u2019Ebre <strong>os trasladar\u00e1 a sus m\u00e1s de 3.300 km2 de superf\u00edcie<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Descubrir nuevos sitios tambi\u00e9n se puede hacer gracias al podcasting. A trav\u00e9s de c\u00e1psulas que nos ayudan a entender e interpretar el territorio, juntamos dos mundos: el turismo y el podcast. Es el caso de las Terres de l\u2019Ebre, con el podcast Rincones por Descubrir de las Terres de l\u2019Ebre. Mediante una audiodescripcci\u00f3n de los [&#8230;]\n","protected":false},"author":1,"featured_media":336,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-335","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-proyectos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Turismo y podcasting, una nueva forma de conocer el territorio - Podcast Estudios<\/title>\n<meta name=\"description\" content=\"Somos creadores de contenidos de audio. En el a\u00f1o 2013 pusimos en marcha R\u00e0dio Ciutat de Tarragona (una de las primeras radios en l\u00ednea del estado). Actualmente gestionamos tres radios en l\u00ednea y creamos podcast corporativos para empresas. Somos una productora local que produce contenidos de consumo de proximidad, nacional e internacional. M\u00e1s de un mill\u00f3n de descargas anuales avalan nuestro proyecto y nuestra experiencia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/podcastestudios.com\/es\/turismo-y-podcasting-una-nueva-forma-de-conocer-el-territorio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Turismo y podcasting, una nueva forma de conocer el territorio - Podcast Estudios\" \/>\n<meta property=\"og:description\" content=\"Somos creadores de contenidos de audio. En el a\u00f1o 2013 pusimos en marcha R\u00e0dio Ciutat de Tarragona (una de las primeras radios en l\u00ednea del estado). Actualmente gestionamos tres radios en l\u00ednea y creamos podcast corporativos para empresas. Somos una productora local que produce contenidos de consumo de proximidad, nacional e internacional. M\u00e1s de un mill\u00f3n de descargas anuales avalan nuestro proyecto y nuestra experiencia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/podcastestudios.com\/es\/turismo-y-podcasting-una-nueva-forma-de-conocer-el-territorio\/\" \/>\n<meta property=\"og:site_name\" content=\"Podcast Estudios\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-16T14:07:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-02T09:25:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/podcastestudios.com\/wp-content\/uploads\/2021\/09\/Les-Cases-Alcanar-e1631197209235.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/podcastestudios.com\\\/es\\\/turismo-y-podcasting-una-nueva-forma-de-conocer-el-territorio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/podcastestudios.com\\\/es\\\/turismo-y-podcasting-una-nueva-forma-de-conocer-el-territorio\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/podcastestudios.com\\\/#\\\/schema\\\/person\\\/d01ffc8ec586e4963071d0338db0c3b4\"},\"headline\":\"Turismo y podcasting, una nueva forma de conocer el territorio\",\"datePublished\":\"2021-09-16T14:07:16+00:00\",\"dateModified\":\"2021-10-02T09:25:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/podcastestudios.com\\\/es\\\/turismo-y-podcasting-una-nueva-forma-de-conocer-el-territorio\\\/\"},\"wordCount\":262,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/podcastestudios.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/podcastestudios.com\\\/es\\\/turismo-y-podcasting-una-nueva-forma-de-conocer-el-territorio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/podcastestudios.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Les-Cases-Alcanar-e1631197209235.jpg\",\"articleSection\":[\"Proyectos (cast)\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/podcastestudios.com\\\/es\\\/turismo-y-podcasting-una-nueva-forma-de-conocer-el-territorio\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/podcastestudios.com\\\/es\\\/turismo-y-podcasting-una-nueva-forma-de-conocer-el-territorio\\\/\",\"url\":\"https:\\\/\\\/podcastestudios.com\\\/es\\\/turismo-y-podcasting-una-nueva-forma-de-conocer-el-territorio\\\/\",\"name\":\"Turismo y podcasting, una nueva forma de conocer el territorio - Podcast Estudios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/podcastestudios.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/podcastestudios.com\\\/es\\\/turismo-y-podcasting-una-nueva-forma-de-conocer-el-territorio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/podcastestudios.com\\\/es\\\/turismo-y-podcasting-una-nueva-forma-de-conocer-el-territorio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/podcastestudios.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Les-Cases-Alcanar-e1631197209235.jpg\",\"datePublished\":\"2021-09-16T14:07:16+00:00\",\"dateModified\":\"2021-10-02T09:25:14+00:00\",\"description\":\"Somos creadores de contenidos de audio. En el a\u00f1o 2013 pusimos en marcha R\u00e0dio Ciutat de Tarragona (una de las primeras radios en l\u00ednea del estado). Actualmente gestionamos tres radios en l\u00ednea y creamos podcast corporativos para empresas. Somos una productora local que produce contenidos de consumo de proximidad, nacional e internacional. M\u00e1s de un mill\u00f3n de descargas anuales avalan nuestro proyecto y nuestra experiencia.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/podcastestudios.com\\\/es\\\/turismo-y-podcasting-una-nueva-forma-de-conocer-el-territorio\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/podcastestudios.com\\\/es\\\/turismo-y-podcasting-una-nueva-forma-de-conocer-el-territorio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/podcastestudios.com\\\/es\\\/turismo-y-podcasting-una-nueva-forma-de-conocer-el-territorio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/podcastestudios.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Les-Cases-Alcanar-e1631197209235.jpg\",\"contentUrl\":\"https:\\\/\\\/podcastestudios.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Les-Cases-Alcanar-e1631197209235.jpg\",\"width\":600,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/podcastestudios.com\\\/es\\\/turismo-y-podcasting-una-nueva-forma-de-conocer-el-territorio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/podcastestudios.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Turismo y podcasting, una nueva forma de conocer el territorio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/podcastestudios.com\\\/#website\",\"url\":\"https:\\\/\\\/podcastestudios.com\\\/\",\"name\":\"Podcast Estudios\",\"description\":\"Somos creadores de contenidos de audio. En el a\u00f1o 2013 pusimos en marcha R\u00e0dio Ciutat de Tarragona (una de las primeras radios en l\u00ednea del estado). Actualmente gestionamos tres radios en l\u00ednea y creamos podcast corporativos para empresas. Somos una productora local que produce contenidos de consumo de proximidad, nacional e internacional. M\u00e1s de un mill\u00f3n de descargas anuales avalan nuestro proyecto y nuestra experiencia.\",\"publisher\":{\"@id\":\"https:\\\/\\\/podcastestudios.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/podcastestudios.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/podcastestudios.com\\\/#organization\",\"name\":\"Podcast Estudios\",\"url\":\"https:\\\/\\\/podcastestudios.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/podcastestudios.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/podcastestudios.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo_esp2-01.svg\",\"contentUrl\":\"https:\\\/\\\/podcastestudios.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo_esp2-01.svg\",\"width\":1,\"height\":1,\"caption\":\"Podcast Estudios\"},\"image\":{\"@id\":\"https:\\\/\\\/podcastestudios.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/podcastestudios.com\\\/#\\\/schema\\\/person\\\/d01ffc8ec586e4963071d0338db0c3b4\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d823517b9e51c132753b152d5f91b571bf18272ed15c5d7c6b29dd1acc679c2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d823517b9e51c132753b152d5f91b571bf18272ed15c5d7c6b29dd1acc679c2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d823517b9e51c132753b152d5f91b571bf18272ed15c5d7c6b29dd1acc679c2?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/tarragonapodcast.com\"],\"url\":\"https:\\\/\\\/podcastestudios.com\\\/es\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Turismo y podcasting, una nueva forma de conocer el territorio - Podcast Estudios","description":"Somos creadores de contenidos de audio. En el a\u00f1o 2013 pusimos en marcha R\u00e0dio Ciutat de Tarragona (una de las primeras radios en l\u00ednea del estado). Actualmente gestionamos tres radios en l\u00ednea y creamos podcast corporativos para empresas. Somos una productora local que produce contenidos de consumo de proximidad, nacional e internacional. M\u00e1s de un mill\u00f3n de descargas anuales avalan nuestro proyecto y nuestra experiencia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/podcastestudios.com\/es\/turismo-y-podcasting-una-nueva-forma-de-conocer-el-territorio\/","og_locale":"es_ES","og_type":"article","og_title":"Turismo y podcasting, una nueva forma de conocer el territorio - Podcast Estudios","og_description":"Somos creadores de contenidos de audio. En el a\u00f1o 2013 pusimos en marcha R\u00e0dio Ciutat de Tarragona (una de las primeras radios en l\u00ednea del estado). Actualmente gestionamos tres radios en l\u00ednea y creamos podcast corporativos para empresas. Somos una productora local que produce contenidos de consumo de proximidad, nacional e internacional. M\u00e1s de un mill\u00f3n de descargas anuales avalan nuestro proyecto y nuestra experiencia.","og_url":"https:\/\/podcastestudios.com\/es\/turismo-y-podcasting-una-nueva-forma-de-conocer-el-territorio\/","og_site_name":"Podcast Estudios","article_published_time":"2021-09-16T14:07:16+00:00","article_modified_time":"2021-10-02T09:25:14+00:00","og_image":[{"width":600,"height":450,"url":"https:\/\/podcastestudios.com\/wp-content\/uploads\/2021\/09\/Les-Cases-Alcanar-e1631197209235.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/podcastestudios.com\/es\/turismo-y-podcasting-una-nueva-forma-de-conocer-el-territorio\/#article","isPartOf":{"@id":"https:\/\/podcastestudios.com\/es\/turismo-y-podcasting-una-nueva-forma-de-conocer-el-territorio\/"},"author":{"name":"admin","@id":"https:\/\/podcastestudios.com\/#\/schema\/person\/d01ffc8ec586e4963071d0338db0c3b4"},"headline":"Turismo y podcasting, una nueva forma de conocer el territorio","datePublished":"2021-09-16T14:07:16+00:00","dateModified":"2021-10-02T09:25:14+00:00","mainEntityOfPage":{"@id":"https:\/\/podcastestudios.com\/es\/turismo-y-podcasting-una-nueva-forma-de-conocer-el-territorio\/"},"wordCount":262,"commentCount":0,"publisher":{"@id":"https:\/\/podcastestudios.com\/#organization"},"image":{"@id":"https:\/\/podcastestudios.com\/es\/turismo-y-podcasting-una-nueva-forma-de-conocer-el-territorio\/#primaryimage"},"thumbnailUrl":"https:\/\/podcastestudios.com\/wp-content\/uploads\/2021\/09\/Les-Cases-Alcanar-e1631197209235.jpg","articleSection":["Proyectos (cast)"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/podcastestudios.com\/es\/turismo-y-podcasting-una-nueva-forma-de-conocer-el-territorio\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/podcastestudios.com\/es\/turismo-y-podcasting-una-nueva-forma-de-conocer-el-territorio\/","url":"https:\/\/podcastestudios.com\/es\/turismo-y-podcasting-una-nueva-forma-de-conocer-el-territorio\/","name":"Turismo y podcasting, una nueva forma de conocer el territorio - Podcast Estudios","isPartOf":{"@id":"https:\/\/podcastestudios.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/podcastestudios.com\/es\/turismo-y-podcasting-una-nueva-forma-de-conocer-el-territorio\/#primaryimage"},"image":{"@id":"https:\/\/podcastestudios.com\/es\/turismo-y-podcasting-una-nueva-forma-de-conocer-el-territorio\/#primaryimage"},"thumbnailUrl":"https:\/\/podcastestudios.com\/wp-content\/uploads\/2021\/09\/Les-Cases-Alcanar-e1631197209235.jpg","datePublished":"2021-09-16T14:07:16+00:00","dateModified":"2021-10-02T09:25:14+00:00","description":"Somos creadores de contenidos de audio. En el a\u00f1o 2013 pusimos en marcha R\u00e0dio Ciutat de Tarragona (una de las primeras radios en l\u00ednea del estado). Actualmente gestionamos tres radios en l\u00ednea y creamos podcast corporativos para empresas. Somos una productora local que produce contenidos de consumo de proximidad, nacional e internacional. M\u00e1s de un mill\u00f3n de descargas anuales avalan nuestro proyecto y nuestra experiencia.","breadcrumb":{"@id":"https:\/\/podcastestudios.com\/es\/turismo-y-podcasting-una-nueva-forma-de-conocer-el-territorio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/podcastestudios.com\/es\/turismo-y-podcasting-una-nueva-forma-de-conocer-el-territorio\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/podcastestudios.com\/es\/turismo-y-podcasting-una-nueva-forma-de-conocer-el-territorio\/#primaryimage","url":"https:\/\/podcastestudios.com\/wp-content\/uploads\/2021\/09\/Les-Cases-Alcanar-e1631197209235.jpg","contentUrl":"https:\/\/podcastestudios.com\/wp-content\/uploads\/2021\/09\/Les-Cases-Alcanar-e1631197209235.jpg","width":600,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/podcastestudios.com\/es\/turismo-y-podcasting-una-nueva-forma-de-conocer-el-territorio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/podcastestudios.com\/es\/"},{"@type":"ListItem","position":2,"name":"Turismo y podcasting, una nueva forma de conocer el territorio"}]},{"@type":"WebSite","@id":"https:\/\/podcastestudios.com\/#website","url":"https:\/\/podcastestudios.com\/","name":"Podcast Estudios","description":"Somos creadores de contenidos de audio. En el a\u00f1o 2013 pusimos en marcha R\u00e0dio Ciutat de Tarragona (una de las primeras radios en l\u00ednea del estado). Actualmente gestionamos tres radios en l\u00ednea y creamos podcast corporativos para empresas. Somos una productora local que produce contenidos de consumo de proximidad, nacional e internacional. M\u00e1s de un mill\u00f3n de descargas anuales avalan nuestro proyecto y nuestra experiencia.","publisher":{"@id":"https:\/\/podcastestudios.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/podcastestudios.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/podcastestudios.com\/#organization","name":"Podcast Estudios","url":"https:\/\/podcastestudios.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/podcastestudios.com\/#\/schema\/logo\/image\/","url":"https:\/\/podcastestudios.com\/wp-content\/uploads\/2021\/09\/logo_esp2-01.svg","contentUrl":"https:\/\/podcastestudios.com\/wp-content\/uploads\/2021\/09\/logo_esp2-01.svg","width":1,"height":1,"caption":"Podcast Estudios"},"image":{"@id":"https:\/\/podcastestudios.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/podcastestudios.com\/#\/schema\/person\/d01ffc8ec586e4963071d0338db0c3b4","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/7d823517b9e51c132753b152d5f91b571bf18272ed15c5d7c6b29dd1acc679c2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7d823517b9e51c132753b152d5f91b571bf18272ed15c5d7c6b29dd1acc679c2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7d823517b9e51c132753b152d5f91b571bf18272ed15c5d7c6b29dd1acc679c2?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/tarragonapodcast.com"],"url":"https:\/\/podcastestudios.com\/es\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/podcastestudios.com\/es\/wp-json\/wp\/v2\/posts\/335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/podcastestudios.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/podcastestudios.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/podcastestudios.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/podcastestudios.com\/es\/wp-json\/wp\/v2\/comments?post=335"}],"version-history":[{"count":7,"href":"https:\/\/podcastestudios.com\/es\/wp-json\/wp\/v2\/posts\/335\/revisions"}],"predecessor-version":[{"id":388,"href":"https:\/\/podcastestudios.com\/es\/wp-json\/wp\/v2\/posts\/335\/revisions\/388"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/podcastestudios.com\/es\/wp-json\/wp\/v2\/media\/336"}],"wp:attachment":[{"href":"https:\/\/podcastestudios.com\/es\/wp-json\/wp\/v2\/media?parent=335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/podcastestudios.com\/es\/wp-json\/wp\/v2\/categories?post=335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/podcastestudios.com\/es\/wp-json\/wp\/v2\/tags?post=335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}